{"id":7273,"date":"2019-02-25T19:37:00","date_gmt":"2019-02-25T19:37:00","guid":{"rendered":"https:\/\/neovisconsulting.co.mz\/\/\/?page_id=7273"},"modified":"2024-04-12T15:32:27","modified_gmt":"2024-04-12T15:32:27","slug":"contactos","status":"publish","type":"page","link":"https:\/\/neovisconsulting.co.mz\/pt-pt\/contactos\/","title":{"rendered":"Contactos"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<style type=\"text\/css\">#nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { min-height: 360px; } #nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { height: calc( 620 * 100vw \/ 1600 ); } <\/style><div data-midnight=\"nectar-slider\" class=\"parallax_slider_outer \"><div  data-transition=\"slide\" data-overall_style=\"classic\" data-flexible-height=\"true\" data-animate-in-effect=\"none\" data-fullscreen=\"false\" data-button-sizing=\"regular\" data-button-styling=\"btn_with_count\" data-autorotate=\"\" data-parallax=\"true\" data-parallax-disable-mobile=\"\" data-caption-trans=\"fade_in_from_bottom\" data-parallax-style=\"bg_only\" data-bg-animation=\"none\" data-full-width=\"true\" class=\"nectar-slider-wrap \" id=\"nectar-slider-instance-1\"><div class=\"swiper-container\"  data-tho=\"auto\" data-tco=\"auto\" data-pho=\"auto\" data-pco=\"auto\" data-loop=\"false\" data-height=\"620\" data-min-height=\"360\" data-arrows=\"false\" data-bullets=\"false\" data-bullet_style=\"see_through\" data-bullet_position=\"bottom\" data-desktop-swipe=\"false\" data-settings=\"\"> <div class=\"swiper-wrapper\"><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"top\" data-color-scheme=\"light\" data-x-pos=\"centered\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/neovisconsulting.co.mz\/wp-content\/uploads\/2019\/02\/Neovis_wall_01-copy.jpg);\"> &nbsp; <\/div><\/div><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h2 class=\"ns-heading-el\">Obrigado pelo seu interesse na Neovis<\/h2><p  ><span>entraremos em contacto com a maior brevidade poss\u00edvel<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture active_texture\"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><\/div><div class=\"nectar-slider-loading \"> <span class=\"loading-icon none\">   <\/span> <\/div> <\/div> \n\t\t\t\t\t\n\t\t\t\t\t<\/div><\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;70&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]<b><u>Morada:<\/u><\/b><br \/>\nRua do Tchamba, 378<br \/>\nMaputo, Mo\u00e7ambique[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text text_direction=&#8221;default&#8221;]<b><u>Telefone:<\/u><\/b><br \/>\n+258 21 489 203<br \/>\n+258 872 034 669<\/p>\n<p><b><u>Email:<\/u><\/b><br \/>\ninfo@neovisconsulting.co.mz[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;50&#8243; bottom_padding=&#8221;50&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_gmap map_type=&#8221;google&#8221; zoom=&#8221;18&#8243; enable_zoom=&#8221;1&#8243; marker_style=&#8221;nectar&#8221; nectar_marker_color=&#8221;accent-color&#8221; size=&#8221;720&#8243; map_center_lat=&#8221;-25.9643483&#8243; map_center_lng=&#8221;32.5922599&#8243; map_markers=&#8221;-25.9643483 | 32.5922599 | NEOVIS HQ&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;55&#8243; bottom_padding=&#8221;55&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][fancy_box box_style=&#8221;default&#8221; icon_family=&#8221;none&#8221; image_url=&#8221;6607&#8243; color=&#8221;Accent-Color&#8221; border_radius=&#8221;default&#8221; image_loading=&#8221;default&#8221; link_url=&#8221;\/pt-pt\/contactos\/contacte-nos\/&#8221; link_text=&#8221;CONTACTAR&#8221; min_height=&#8221;155&#8243;]\n<h3 style=\"text-align: center;\">Envie-nos as suas quest\u00f5es<\/h3>\n[\/fancy_box][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][fancy_box box_style=&#8221;default&#8221; icon_family=&#8221;none&#8221; image_url=&#8221;6608&#8243; color=&#8221;Accent-Color&#8221; border_radius=&#8221;default&#8221; image_loading=&#8221;default&#8221; link_url=&#8221;\/pt-pt\/contactos\/candidatura\/&#8221; link_text=&#8221;ENVIAR CV&#8221; min_height=&#8221;155&#8243;]\n<h3 style=\"text-align: center;\">Reforce a nossa equipa<\/h3>\n[\/fancy_box][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][fancy_box box_style=&#8221;default&#8221; icon_family=&#8221;none&#8221; image_url=&#8221;6438&#8243; color=&#8221;Accent-Color&#8221; border_radius=&#8221;default&#8221; image_loading=&#8221;default&#8221; link_url=&#8221;\/pt-pt\/contactos\/submissao-de-rfp\/&#8221; link_text=&#8221;ENVIAR RFP\/RFI&#8221; min_height=&#8221;155&#8243;]\n<h3 style=\"text-align: center;\">Envie-nos o seu pedido de informa\u00e7\u00e3o e\/ou proposta (RFI\/RFP)<\/h3>\n[\/fancy_box][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":40,"comment_status":"closed","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"class_list":["post-7273","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contactos - Neovis Consulting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/neovisconsulting.co.mz\/pt-pt\/contactos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contactos - Neovis Consulting\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/neovisconsulting.co.mz\/pt-pt\/contactos\/\" \/>\n<meta property=\"og:site_name\" content=\"Neovis Consulting\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-12T15:32:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/neovisconsulting.co.mz\/wp-content\/uploads\/2024\/04\/neovis-circle2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/neovisconsulting.co.mz\\\/pt-pt\\\/contactos\\\/\",\"url\":\"https:\\\/\\\/neovisconsulting.co.mz\\\/pt-pt\\\/contactos\\\/\",\"name\":\"Contactos - Neovis Consulting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/neovisconsulting.co.mz\\\/#website\"},\"datePublished\":\"2019-02-25T19:37:00+00:00\",\"dateModified\":\"2024-04-12T15:32:27+00:00\",\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/neovisconsulting.co.mz\\\/pt-pt\\\/contactos\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/neovisconsulting.co.mz\\\/#website\",\"url\":\"https:\\\/\\\/neovisconsulting.co.mz\\\/\",\"name\":\"Neovis Consulting\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/neovisconsulting.co.mz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contactos - Neovis Consulting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/neovisconsulting.co.mz\/pt-pt\/contactos\/","og_locale":"pt_PT","og_type":"article","og_title":"Contactos - Neovis Consulting","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221;...","og_url":"https:\/\/neovisconsulting.co.mz\/pt-pt\/contactos\/","og_site_name":"Neovis Consulting","article_modified_time":"2024-04-12T15:32:27+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/neovisconsulting.co.mz\/wp-content\/uploads\/2024\/04\/neovis-circle2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/neovisconsulting.co.mz\/pt-pt\/contactos\/","url":"https:\/\/neovisconsulting.co.mz\/pt-pt\/contactos\/","name":"Contactos - Neovis Consulting","isPartOf":{"@id":"https:\/\/neovisconsulting.co.mz\/#website"},"datePublished":"2019-02-25T19:37:00+00:00","dateModified":"2024-04-12T15:32:27+00:00","inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/neovisconsulting.co.mz\/pt-pt\/contactos\/"]}]},{"@type":"WebSite","@id":"https:\/\/neovisconsulting.co.mz\/#website","url":"https:\/\/neovisconsulting.co.mz\/","name":"Neovis Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/neovisconsulting.co.mz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/neovisconsulting.co.mz\/pt-pt\/wp-json\/wp\/v2\/pages\/7273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/neovisconsulting.co.mz\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/neovisconsulting.co.mz\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/neovisconsulting.co.mz\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/neovisconsulting.co.mz\/pt-pt\/wp-json\/wp\/v2\/comments?post=7273"}],"version-history":[{"count":5,"href":"https:\/\/neovisconsulting.co.mz\/pt-pt\/wp-json\/wp\/v2\/pages\/7273\/revisions"}],"predecessor-version":[{"id":7563,"href":"https:\/\/neovisconsulting.co.mz\/pt-pt\/wp-json\/wp\/v2\/pages\/7273\/revisions\/7563"}],"wp:attachment":[{"href":"https:\/\/neovisconsulting.co.mz\/pt-pt\/wp-json\/wp\/v2\/media?parent=7273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}